{"id":7058,"date":"2021-08-10T20:54:19","date_gmt":"2021-08-11T00:54:19","guid":{"rendered":"https:\/\/healthcliner.com\/cancro-do-ovario-estagios-e-tratamentos\/"},"modified":"2021-08-10T20:54:21","modified_gmt":"2021-08-11T00:54:21","slug":"cancro-do-ovario-estagios-e-tratamentos","status":"publish","type":"post","link":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/","title":{"rendered":"Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos"},"content":{"rendered":"<p>Proeminentemente, entre as causas mais significativas de mortalidade e morbilidade no mundo est\u00e1 o cancro. Principalmente, as complica\u00e7\u00f5es do cancro s\u00e3o caracterizadas pela prolifera\u00e7\u00e3o de c\u00e9lulas descontroladas e cont\u00ednuas e espalhando-se para os tecidos circundantes. Notavelmente, o cancro do ov\u00e1rio est\u00e1 atualmente na lideran\u00e7a no traumatizamento da sa\u00fade reprodutiva das mulheres. \u00c9 digno de notar que o cancro do ov\u00e1rio compreende m\u00faltiplas condi\u00e7\u00f5es doentes dos ov\u00e1rios. Existem tipos de cancro do ov\u00e1rio, dependendo da morfologia sob o microsc\u00f3pio e do seu tratamento e progn\u00f3stico. O cancro do ov\u00e1rio \u00e9 geralmente confundido com outros problemas comuns devido \u00e0 sua natureza subtil. Na maioria dos casos, o cancro do ov\u00e1rio s\u00f3 apresenta sintomas numa fase avan\u00e7ada. No entanto, os sinais e sintomas de v\u00e1rios cancros do ov\u00e1rio parecem apresentar algumas propriedades semelhantes. Os tumores do ov\u00e1rio nunca devem ser confundidos com quistos do ov\u00e1rio. Enquanto os tumores do ov\u00e1rio s\u00e3o massas s\u00f3lidas, os quistos do ov\u00e1rio s\u00e3o geralmente cheios de fluidos.<\/p>\n<p>Notavelmente, os fatores de risco mais elevados s\u00e3o considerados a raiz do cancro do ov\u00e1rio. O passado de um parente do cancro do ov\u00e1rio est\u00e1 entre os fatores de amea\u00e7a significativos associados ao aparecimento do cancro do ov\u00e1rio. A raz\u00e3o por detr\u00e1s do risco da hist\u00f3ria familiar est\u00e1 ligada a quest\u00f5es heredit\u00e1rias. Embora se supunha que \u00e9 respons\u00e1vel por uma percentagem menor de f\u00eameas com malignidade do ov\u00e1rio, tem de ser considerado um fator de risco vital. Marcadamente, um hist\u00f3rico familiar de cancros uterinos, retal, c\u00f3lon, mama e ov\u00e1rio indicam um risco aumentado para os progenios. Embora nenhuma muta\u00e7\u00e3o gen\u00e9tica seja diagnosticada nesses pacientes, o risco aumentado de cancro do ov\u00e1rio ainda prevalece. Al\u00e9m disso, o hist\u00f3rico pessoal de cancro ou mesmo a endometriose \u00e9 indicativo de um risco aumentado de cancro do ov\u00e1rio.<\/p>\n<p>Al\u00e9m disso, as muta\u00e7\u00f5es gen\u00e9ticas em genes ligados ao cancro do ov\u00e1rio, como os genes BRCA2 e BRCA1, culminam no cancro do ov\u00e1rio. Assim, as muta\u00e7\u00f5es gen\u00e9ticas est\u00e3o entre as causas fundamentais do cancro do ov\u00e1rio. Na maior parte das vezes, as muta\u00e7\u00f5es nos cancros da mama 1 e 2 s\u00e3o heredit\u00e1rias. Al\u00e9m disso, est\u00e3o ligados ao cancro da mama e do ov\u00e1rio, aumentando assim a possibilidade de cancro do ov\u00e1rio. Al\u00e9m disso, a s\u00edndrome gen\u00e9tica do cancro colorretal n\u00e3o pol\u00e9mico heredit\u00e1rio (HNPCC) tamb\u00e9m est\u00e1 geneticamente ligada ao cancro do ov\u00e1rio. Cerca de 12% das mulheres com HNPCC t\u00eam uma amea\u00e7a acrescida de ter cancro do ov\u00e1rio nas suas vidas. Al\u00e9m disso, embora as mulheres estejam na possibilidade de ter tumor no ov\u00e1rio em qualquer idade, as mulheres idosas representam uma percentagem mais elevada entre as que t\u00eam cancro do ov\u00e1rio. Al\u00e9m disso, o rem\u00e9dio para as mulheres na menopausa, a terap\u00eautica de substitui\u00e7\u00e3o hormonal, est\u00e1 ligado a uma possibilidade proliferada de ter tumores do ov\u00e1rio, especialmente para as f\u00eameas que n\u00e3o foram submetidas a uma histerectomia.<\/p>\n<p>O cancro do ov\u00e1rio \u00e9 observado para ter v\u00e1rias fases. O cancro do ov\u00e1rio de fase 1 tem um excelente progn\u00f3stico estabelecido. A taxa de sobreviv\u00eancia das fases 1A e 1B \u00e9 de cinco anos para 90% dos pacientes com tumores de grau 1. A histerectomia \u00e9 considerada o tratamento perfeito para o cancro do ov\u00e1rio de fase 1, onde tanto os ov\u00e1rios como as trompas de fal\u00f3pio s\u00e3o removidos. Dependendo da interpreta\u00e7\u00e3o do patologista, o tratamento adicional pode ser desnecess\u00e1rio se o tumor for de baixa qualidade. No entanto, a quimioterapia combinada pode ser necess\u00e1ria quando o cancro \u00e9 de alta qualidade. O cancro do ov\u00e1rio de fase 2 implica que o cancro j\u00e1 se espalhou para um \u00fanico ou dois ov\u00e1rios e tem disseminado para a maioria dos \u00f3rg\u00e3os dentro da p\u00e9lvis. O cancro do ov\u00e1rio da fase 2A \u00e9 quando o tumor se disseminou para o oviduto e o \u00fatero. Quando o cancro penetrou nos tecidos da p\u00e9lvis, a fase \u00e9 denotada como fase 2B. Na fase 2C, o cancro j\u00e1 se espalhou para outros tecidos dentro da p\u00e9lvis e do \u00fatero. Al\u00e9m disso, as trompas de fal\u00f3pio s\u00e3o esta fase onde as c\u00e9lulas cancer\u00edgenas podem ser encontradas na abertura peritoneal. Cerca de 70% das v\u00edtimas nesta fase t\u00eam uma taxa de sobreviv\u00eancia de cinco anos. Salpingo-ooforectomia bilateral e histerectomia s\u00e3o os procedimentos cir\u00fargicos para os pacientes na fase 2. Al\u00e9m disso, a quimioterapia combinada com ou sem radioterapia pode ser o tratamento recomendado ap\u00f3s o procedimento cir\u00fargico.<\/p>\n<p>O cancro do ov\u00e1rio de fase 3 implica que o cancro se disseminou para um \u00fanico ou dois ov\u00e1rios em torno da p\u00e9lvis e entrou em partes do est\u00f4mago e em torno das protuber\u00e2ncias linf\u00e1ticas. A fase 3A \u00e9 onde o cancro s\u00f3 \u00e9 encontrado na regi\u00e3o da p\u00e9lvis e pode ser microscopicamente visto dentro dos tecidos do peritoneum. Sob a fase 3B, o tumor disseminou para o peritoneum, e o crescimento \u00e9 cerca de 2 cm de comprimento ou mesmo menor. Na fase 3C, o cancro dentro do peritoneum \u00e9 mais significativo do que 2cm e espalhou-se para os n\u00f3dulos linf\u00e1ticos. Cerca de 39% dos doentes com cancro do ov\u00e1rio t\u00eam uma taxa de sobreviv\u00eancia de cinco anos. A histerectomia e a salpingo-ooforectomia, al\u00e9m de debular tumores em torno dos n\u00f3dulos linf\u00e1ticos e da p\u00e9lvis e do abd\u00f3men, s\u00e3o os procedimentos cir\u00fargicos preferidos. Recomenda-se quimioterapia combinada seguida de cirurgia adicional. O crescimento do ov\u00e1rio da fase 4 implica que o cancro se moveu para fora do est\u00f4mago para v\u00e1rias partes do corpo, como pulm\u00f5es ou mesmo f\u00edgado. A taxa de sobreviv\u00eancia \u00e9 escassa, onde apenas 17% dos pacientes t\u00eam uma taxa de sobreviv\u00eancia de cinco anos. A remo\u00e7\u00e3o cir\u00fargica dos tecidos cancer\u00edgenos tanto quanto poss\u00edvel, juntamente com a quimioterapia combinada, \u00e9 o rem\u00e9dio recomendado.<\/p>\n<p>Notavelmente, o tratamento do cancro do ov\u00e1rio envolve terapias locais e sist\u00e9micas. O tipo de tratamento considerado como terapia local inclui aqueles que tratam o tumor sem afetar outras partes do corpo. As respetivas terapias locais do cancro do ov\u00e1rio s\u00e3o a radioterapia para o cancro do ov\u00e1rio e a cirurgia para o cancro do ov\u00e1rio. Consideravelmente, a cirurgia para o cancro do ov\u00e1rio \u00e9 o tratamento prim\u00e1rio preferido na gest\u00e3o do cancro. A quantidade de cirurgia a realizar depende da dist\u00e2ncia que o cancro se espalhou e da sa\u00fade corporal. As mulheres que podem ter filhos com tumores e cancro na fase inicial s\u00e3o tratadas sem remover os ov\u00e1rios e o \u00fatero. Mais uma vez, h\u00e1 dois objetivos principais na cirurgia do cancro do ov\u00e1rio epitelial, debulhamento e encena\u00e7\u00e3o. A cirurgia n\u00e3o \u00e9 apropriada quando o cancro n\u00e3o \u00e9 encenado e debulhado. A encena\u00e7\u00e3o do cancro do ov\u00e1rio epitelial \u00e9 necess\u00e1ria para observar a propaga\u00e7\u00e3o do cancro do ov\u00e1rio. A remo\u00e7\u00e3o do \u00fatero \u00e9 chamada histerectomia; quando envolve a remo\u00e7\u00e3o de trompas de fal\u00f3pio e ambos os ov\u00e1rios, \u00e9 chamado salpingo-ooforectomia bilateral (BSO). Normalmente, a opera\u00e7\u00e3o envolve a remo\u00e7\u00e3o do omento, e um processo chamado omentectomia. \u00c0s vezes, o cancro espalha-se para o omento, uma \u00e1rea que cobre o conte\u00fado abdominal.<\/p>\n<p>Al\u00e9m disso, o debulhamento do cancro do ov\u00e1rio epitelial forma outro objetivo cr\u00edtico da cirurgia do cancro do ov\u00e1rio, que visa remover muitos tumores n\u00e3o deixando tumores vis\u00edveis. O debulhamento \u00e9 mais importante na propaga\u00e7\u00e3o do cancro do ov\u00e1rio no abd\u00f3men durante a cirurgia. Os pacientes com tumores idealmente debulcados apresentam um melhor progn\u00f3stico em compara\u00e7\u00e3o com aqueles com tumores maiores durante a cirurgia. Em alguns casos, a cirurgia destina-se a remover o cancro em tumores do ov\u00e1rio e das c\u00e9lulas germinativas do ov\u00e1rio. A salpingo-ooforectomia bilateral e a histerectomia s\u00e3o usadas no tratamento da maioria dos tumores do ov\u00e1rio. Se o cancro est\u00e1 num ov\u00e1rio e se quer ter filhos, o tratamento implicaria remover o ov\u00e1rio e a trompa de fal\u00f3pio que cont\u00e9m cancro. Mais tecidos precisam de ser removidos quando o cancro se espalhou por todo o lado no ov\u00e1rio; isto exigiria tanto salpingo-ooforectomia bilateral, histerectomia e cirurgia de debulhamento.<\/p>\n<p>Marcadamente, a terapia sist\u00e9mica engloba o uso de f\u00e1rmacos no tratamento do cancro do ov\u00e1rio. Os f\u00e1rmacos usados s\u00e3o conhecidos como terapias sist\u00e9micas devido \u00e0 sua capacidade de chegar \u00e0s c\u00e9lulas cancer\u00edgenas em todo o corpo. As drogas s\u00e3o administradas diretamente na corrente sangu\u00ednea ou podem ser administradas oralmente. Com base no cancro do ov\u00e1rio, o tratamento do f\u00e1rmaco pode compor terapia hormonal, quimioterapia ou terapia direcionada para o cancro do ov\u00e1rio. Notavelmente, as drogas ou hormonas que bloqueiam hormonas s\u00e3o agentes cr\u00edticos na terapia hormonal; lutam contra o cancro. Raramente, o rem\u00e9dio sist\u00e9mico \u00e9 usado para curar o tumor epitelial do ov\u00e1rio e \u00e9 frequentemente utilizado no tratamento do cancro do ov\u00e1rio. Principalmente, os agonistas luteinizantes-libertadores de hormonas (LHRH) s\u00e3o um exemplo de f\u00e1rmacos \u00fateis no tratamento do cancro, que reduzem os n\u00edveis de estrog\u00e9nio nas mulheres pr\u00e9-menop\u00e1usicas. Tais drogas incluem leuprolide e goserelin. Os agonistas do LHRH s\u00e3o administradas por inje\u00e7\u00e3o a cada um a tr\u00eas meses. Alguns dos seus efeitos secund\u00e1rios s\u00e3o sintomas da menopausa, como a secura vaginal e os flashes de calor. Se tomados por um per\u00edodo prolongado, os f\u00e1rmacos podem causar osteoporose.<\/p>\n<p>Outro f\u00e1rmaco nesta categoria \u00e9 o Tamoxifen, e \u00e9 frequentemente usado no tratamento do cancro da mama. Al\u00e9m disso, \u00e9 \u00fatil no tratamento de tumores estro\u00f3ricos do ov\u00e1rio e raramente no controlo do tumor epitelial progressivo do ov\u00e1rio. Tamoxifen funciona como um anti-estrog\u00e9nio em v\u00e1rios corpos s\u00e3o s. A terapia tamoxifena serve para manter os estrog\u00e9nios que circulam no \u00fatero de uma mulher de crescimentos excitantes. Da mesma forma, os inibidores de Aromatase s\u00e3o f\u00e1rmacos sob a categoria LHRH que bloqueiam uma atividade enzim\u00e1tica aromatase, transformando outras hormonas em estrog\u00e9nio quando uma mulher est\u00e1 na p\u00f3s-menopausa. Os f\u00e1rmacos ajudam a baixar os n\u00edveis de estrog\u00e9nio das mulheres ap\u00f3s a menopausa. Principalmente, os f\u00e1rmacos tratam o cancro da mama e os tumores stromal do ov\u00e1rio recorrentes ap\u00f3s o tratamento. As drogas s\u00e3o tomadas uma vez por dia como comprimidos.<\/p>\n<p>Al\u00e9m disso, a quimioterapia \u00e9 outro tratamento sist\u00e9mico no qual os f\u00e1rmacos s\u00e3o usados para tratar o cancro. Desta forma, as drogas entram diretamente na corrente sangu\u00ednea em todas as partes do corpo. A quimioterapia ajuda a matar ou diminuir pequenas quantidades de c\u00e9lulas cancer\u00edgenas encontradas ap\u00f3s a cirurgia, principalmente cancros que se espalharam. A quimioterapia \u00e9 aplicada atrav\u00e9s da inje\u00e7\u00e3o, dada oralmente, ou atrav\u00e9s do cateter, onde \u00e9 injetada diretamente na cavidade abdominal atrav\u00e9s da quimioterapia intraperitoneal. Dois f\u00e1rmacos diferentes s\u00e3o usados juntos na quimioterapia para o cancro do ov\u00e1rio. Os f\u00e1rmacos combinados incluem um composto de platina, que \u00e9 carboplatina ou cisplatina, e um f\u00e1rmaco de quimioterapia referido como taxanes como paclitaxel ou docetaxel. Normalmente, o cancro do ov\u00e1rio epitelial encolhe com quimioterapia, mas as c\u00e9lulas cancer\u00edgenas voltam a crescer ap\u00f3s algum tempo. Ap\u00f3s a aplica\u00e7\u00e3o da primeira quimioterapia e n\u00e3o se v\u00ea nenhuma altera\u00e7\u00e3o percet\u00edvel durante seis a doze meses, a mesma quimioterapia usada pela primeira vez deve ser usada no tratamento. A quimioterapia intraperitoneal \u00e9 dada para al\u00e9m da terapia sist\u00e9mica no tratamento do cancro que n\u00e3o se espalhou nem debulhou. Os tumores estro\u00f3ricos do ov\u00e1rio n\u00e3o s\u00e3o tratados com quimioterapia; em vez disso, s\u00e3o tratados com uma combina\u00e7\u00e3o de paclitaxel com carboplatina. Perder o apetite, a queda de cabelo, a enjoo, o derrame, as les\u00f5es na boca, as erup\u00e7\u00f5es cut\u00e2neas nos p\u00e9s e nas m\u00e3os est\u00e3o entre os efeitos secund\u00e1rios das quimioterapias.<\/p>\n<p>Al\u00e9m disso, a terapia direcionada no cancro do ov\u00e1rio emprega f\u00e1rmacos \u00fateis no ataque e identifica\u00e7\u00e3o de c\u00e9lulas cancer\u00edgenas, causando pequenos danos \u00e0s c\u00e9lulas normais. Este tratamento faz com que o ataque aos forros das c\u00e9lulas cancerosas os programe de forma diferente do normal. A terapia direcionada funciona de forma diferente em cada administra\u00e7\u00e3o, e afetam o crescimento das c\u00e9lulas cancer\u00edgenas, o processo de divis\u00e3o e repara\u00e7\u00e3o, e a sua intera\u00e7\u00e3o com outras c\u00e9lulas. Bevacizumab, um tipo de droga pertence \u00e0 classe dos inibidores da angiog\u00e9nese. O f\u00e1rmaco liga-se ao fator de crescimento endotelial vascular (VEGF), uma esp\u00e9cie de prote\u00edna que sinaliza a forma\u00e7\u00e3o de novos vasos sangu\u00edneos para retardar ou parar o crescimento do cancro. Bevacizumab encolhe ou retarda crescimentos epiteliais avan\u00e7ados associados aos cancros do ov\u00e1rio. Bevacizumab funciona melhor com a quimioterapia, e tamb\u00e9m pode ser dado com Olaparib. Os efeitos secund\u00e1rios do bevacizumab incluem dores de cabe\u00e7a, hipertens\u00e3o, gl\u00f3bulos brancos baixos (WBCs), cansa\u00e7o e sangramento. Outros f\u00e1rmacos \u00fateis no tratamento do cancro do ov\u00e1rio s\u00e3o os inibidores poli-adenosina diphosfato-ribose poli-ribose (PARP), incluindo rucaparib, Olaparib e niraparib. Estes f\u00e1rmacos s\u00e3o conhecidos por retardar ou diminuir os cancros avan\u00e7ados do ov\u00e1rio no tempo; pensa-se que aumentam o tempo de vida das mulheres.<\/p>\n<p>Conclusivamente, nota-se que foram estabelecidos progressos na compreens\u00e3o do cancro do ov\u00e1rio ao longo das eras anteriores. Embora muito persista por ganhar, por exemplo, a origem do cancro do ov\u00e1rio, o seu mecanismo de desenvolvimento, o conhecimento essencial para a sua preven\u00e7\u00e3o e o melhor tratamento. \u00c9 necess\u00e1ria uma comunica\u00e7\u00e3o eficaz no reconhecimento precoce do cancro do ov\u00e1rio e na gest\u00e3o de variedades de cancro do ov\u00e1rio. Devem ser prefer\u00edveis abordagens mais operativas para garantir a auto-gest\u00e3o e os cuidados de apoio \u00e0s mulheres com cancro do ov\u00e1rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proeminentemente, entre as causas mais significativas de mortalidade e morbilidade no mundo est\u00e1 o cancro. Principalmente, as complica\u00e7\u00f5es do cancro s\u00e3o caracterizadas pela prolifera\u00e7\u00e3o de c\u00e9lulas descontroladas e cont\u00ednuas e espalhando-se para os tecidos circundantes. Notavelmente, o cancro do ov\u00e1rio est\u00e1 atualmente na lideran\u00e7a no traumatizamento da sa\u00fade reprodutiva das mulheres. \u00c9 digno de notar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5284,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[116],"tags":[],"class_list":["post-7058","post","type-post","status-publish","format-standard","has-post-thumbnail","category-saude-da-mulher"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos - Healthcliner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos - Healthcliner\" \/>\n<meta property=\"og:description\" content=\"Proeminentemente, entre as causas mais significativas de mortalidade e morbilidade no mundo est\u00e1 o cancro. Principalmente, as complica\u00e7\u00f5es do cancro s\u00e3o caracterizadas pela prolifera\u00e7\u00e3o de c\u00e9lulas descontroladas e cont\u00ednuas e espalhando-se para os tecidos circundantes. Notavelmente, o cancro do ov\u00e1rio est\u00e1 atualmente na lideran\u00e7a no traumatizamento da sa\u00fade reprodutiva das mulheres. \u00c9 digno de notar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/\" \/>\n<meta property=\"og:site_name\" content=\"Healthcliner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/Healthcliner\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-11T00:54:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-11T00:54:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/07\/SU-Design-1627668410.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alfred Amaechi, DNP-FNP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@healthcliner\" \/>\n<meta name=\"twitter:site\" content=\"@healthcliner\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alfred Amaechi, DNP-FNP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/\"},\"author\":{\"name\":\"Alfred Amaechi, DNP-FNP\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/25afea9c4c38e50d96f0a082932b7e98\"},\"headline\":\"Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos\",\"datePublished\":\"2021-08-11T00:54:19+00:00\",\"dateModified\":\"2021-08-11T00:54:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/\"},\"wordCount\":2456,\"publisher\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SU-Design-1627668410.jpg\",\"articleSection\":[\"Sa\u00fade da Mulher\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/\",\"name\":\"Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos - Healthcliner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SU-Design-1627668410.jpg\",\"datePublished\":\"2021-08-11T00:54:19+00:00\",\"dateModified\":\"2021-08-11T00:54:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SU-Design-1627668410.jpg\",\"contentUrl\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SU-Design-1627668410.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/cancro-do-ovario-estagios-e-tratamentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/\",\"name\":\"Healthcliner\",\"description\":\"Evidence-based Health Information\",\"publisher\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#organization\",\"name\":\"Healthcliner\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Small-size-transparent-image-for-web-1.png\",\"contentUrl\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Small-size-transparent-image-for-web-1.png\",\"width\":500,\"height\":101,\"caption\":\"Healthcliner\"},\"image\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/Healthcliner\",\"https:\\\/\\\/x.com\\\/healthcliner\",\"https:\\\/\\\/www.instagram.com\\\/healthcliner\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/Healthcliner\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/25afea9c4c38e50d96f0a082932b7e98\",\"name\":\"Alfred Amaechi, DNP-FNP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/litespeed\\\/avatar\\\/bed4339504369301498480bc573f3293.jpg?ver=1784092360\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/litespeed\\\/avatar\\\/bed4339504369301498480bc573f3293.jpg?ver=1784092360\",\"contentUrl\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/litespeed\\\/avatar\\\/bed4339504369301498480bc573f3293.jpg?ver=1784092360\",\"caption\":\"Alfred Amaechi, DNP-FNP\"},\"description\":\"\",\"sameAs\":[\"https:\\\/\\\/healthcliner.com\"],\"url\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/author\\\/alfred-amaechi-dnp-fnp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos - Healthcliner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/","og_locale":"pt_PT","og_type":"article","og_title":"Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos - Healthcliner","og_description":"Proeminentemente, entre as causas mais significativas de mortalidade e morbilidade no mundo est\u00e1 o cancro. Principalmente, as complica\u00e7\u00f5es do cancro s\u00e3o caracterizadas pela prolifera\u00e7\u00e3o de c\u00e9lulas descontroladas e cont\u00ednuas e espalhando-se para os tecidos circundantes. Notavelmente, o cancro do ov\u00e1rio est\u00e1 atualmente na lideran\u00e7a no traumatizamento da sa\u00fade reprodutiva das mulheres. \u00c9 digno de notar [&hellip;]","og_url":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/","og_site_name":"Healthcliner","article_publisher":"https:\/\/business.facebook.com\/Healthcliner","article_published_time":"2021-08-11T00:54:19+00:00","article_modified_time":"2021-08-11T00:54:21+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/07\/SU-Design-1627668410.jpg","type":"image\/jpeg"}],"author":"Alfred Amaechi, DNP-FNP","twitter_card":"summary_large_image","twitter_creator":"@healthcliner","twitter_site":"@healthcliner","twitter_misc":{"Escrito por":"Alfred Amaechi, DNP-FNP","Tempo estimado de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/#article","isPartOf":{"@id":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/"},"author":{"name":"Alfred Amaechi, DNP-FNP","@id":"https:\/\/healthcliner.com\/pt-pt\/#\/schema\/person\/25afea9c4c38e50d96f0a082932b7e98"},"headline":"Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos","datePublished":"2021-08-11T00:54:19+00:00","dateModified":"2021-08-11T00:54:21+00:00","mainEntityOfPage":{"@id":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/"},"wordCount":2456,"publisher":{"@id":"https:\/\/healthcliner.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/#primaryimage"},"thumbnailUrl":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/07\/SU-Design-1627668410.jpg","articleSection":["Sa\u00fade da Mulher"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/","url":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/","name":"Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos - Healthcliner","isPartOf":{"@id":"https:\/\/healthcliner.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/#primaryimage"},"image":{"@id":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/#primaryimage"},"thumbnailUrl":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/07\/SU-Design-1627668410.jpg","datePublished":"2021-08-11T00:54:19+00:00","dateModified":"2021-08-11T00:54:21+00:00","breadcrumb":{"@id":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/#primaryimage","url":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/07\/SU-Design-1627668410.jpg","contentUrl":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/07\/SU-Design-1627668410.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/healthcliner.com\/pt-pt\/cancro-do-ovario-estagios-e-tratamentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/healthcliner.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Cancro do ov\u00e1rio: Est\u00e1gios e Tratamentos"}]},{"@type":"WebSite","@id":"https:\/\/healthcliner.com\/pt-pt\/#website","url":"https:\/\/healthcliner.com\/pt-pt\/","name":"Healthcliner","description":"Evidence-based Health Information","publisher":{"@id":"https:\/\/healthcliner.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/healthcliner.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/healthcliner.com\/pt-pt\/#organization","name":"Healthcliner","url":"https:\/\/healthcliner.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/healthcliner.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/09\/Small-size-transparent-image-for-web-1.png","contentUrl":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/09\/Small-size-transparent-image-for-web-1.png","width":500,"height":101,"caption":"Healthcliner"},"image":{"@id":"https:\/\/healthcliner.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/Healthcliner","https:\/\/x.com\/healthcliner","https:\/\/www.instagram.com\/healthcliner\/","https:\/\/www.pinterest.com\/Healthcliner\/"]},{"@type":"Person","@id":"https:\/\/healthcliner.com\/pt-pt\/#\/schema\/person\/25afea9c4c38e50d96f0a082932b7e98","name":"Alfred Amaechi, DNP-FNP","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/healthcliner.com\/wp-content\/litespeed\/avatar\/bed4339504369301498480bc573f3293.jpg?ver=1784092360","url":"https:\/\/healthcliner.com\/wp-content\/litespeed\/avatar\/bed4339504369301498480bc573f3293.jpg?ver=1784092360","contentUrl":"https:\/\/healthcliner.com\/wp-content\/litespeed\/avatar\/bed4339504369301498480bc573f3293.jpg?ver=1784092360","caption":"Alfred Amaechi, DNP-FNP"},"description":"","sameAs":["https:\/\/healthcliner.com"],"url":"https:\/\/healthcliner.com\/pt-pt\/author\/alfred-amaechi-dnp-fnp\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/posts\/7058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=7058"}],"version-history":[{"count":1,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/posts\/7058\/revisions"}],"predecessor-version":[{"id":7059,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/posts\/7058\/revisions\/7059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/media\/5284"}],"wp:attachment":[{"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=7058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=7058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=7058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}