{"id":6499,"date":"2021-08-10T04:31:10","date_gmt":"2021-08-10T08:31:10","guid":{"rendered":"https:\/\/healthcliner.com\/regras-e-regulamentos\/"},"modified":"2021-08-10T04:31:23","modified_gmt":"2021-08-10T08:31:23","slug":"regras-e-regulamentos","status":"publish","type":"page","link":"https:\/\/healthcliner.com\/pt-pt\/regras-e-regulamentos\/","title":{"rendered":"Regras e Regulamentos"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-2vw||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto||||||||&#8221; text_text_color=&#8221;rgba(0,0,0,0.75)&#8221; text_font_size=&#8221;16px&#8221; link_font=&#8221;Roboto||||||||&#8221; link_text_color=&#8221;#68d800&#8243; link_font_size=&#8221;16px&#8221; link_option_url=&#8221;https:\/\/www.websitepolicies.com\/policies\/view\/7KXlMwcR&#8221; link_option_url_new_window=&#8221;on&#8221; link_text_color__hover_enabled=&#8221;off|hover&#8221;]<\/p>\n<p><strong>Pol\u00edtica de utiliza\u00e7\u00e3o aceit\u00e1vel<\/strong><\/p>\n<p>Esta pol\u00edtica de utiliza\u00e7\u00e3o aceit\u00e1vel (&#8220;Pol\u00edtica&#8221;) estabelece as orienta\u00e7\u00f5es gerais e as utiliza\u00e7\u00f5es aceit\u00e1veis e proibidas do website healthcliner.com (&#8220;Website&#8221; ou &#8220;Servi\u00e7o&#8221;) e de qualquer um dos seus produtos e servi\u00e7os relacionados (coletivamente, &#8220;Servi\u00e7os&#8221;). Esta Pol\u00edtica \u00e9 um acordo juridicamente vinculativo entre si (&#8220;Utilizador&#8221;, &#8220;voc\u00ea&#8221; ou &#8220;seu&#8221;) e Healthcliner (&#8220;Healthcliner&#8221;, &#8220;n\u00f3s&#8221;, &#8220;n\u00f3s&#8221; ou &#8220;nosso&#8221;). Ao aceder e utilizar o Website e Servi\u00e7os, reconhece que leu, compreendeu e concorda em ficar vinculado aos termos deste Contrato. Se estiver a celebrar este Contrato em nome de uma empresa ou de outra entidade jur\u00eddica, representa que tem autoridade para vincular essa entidade a este Contrato, caso em que os termos &#8220;Utilizador&#8221;, &#8220;voc\u00ea&#8221; ou &#8220;seu&#8221; se referir\u00e3o a essa entidade. Se n\u00e3o tiver essa autoridade, ou se n\u00e3o concordar com os termos deste Contrato, n\u00e3o deve aceitar este Contrato e n\u00e3o poder\u00e1 aceder e utilizar o Website e Servi\u00e7os. Reconhece que este Contrato \u00e9 um contrato entre si e a Healthcliner, mesmo que seja eletr\u00f3nico e n\u00e3o seja fisicamente assinado por si, e rege a sua utiliza\u00e7\u00e3o do Website e Servi\u00e7os.<\/p>\n<p><strong>Atividades e utiliza\u00e7\u00f5es proibidas<\/strong><\/p>\n<p>N\u00e3o pode utilizar o Website e servi\u00e7os para exercer atividades ilegais nos termos da legisla\u00e7\u00e3o aplic\u00e1vel, que sejam prejudiciais para os outros, ou que nos sujeitariam a responsabilidades, incluindo, sem limita\u00e7\u00e3o, em rela\u00e7\u00e3o a qualquer uma das seguintes, cada uma das quais \u00e9 proibida ao abrigo desta Pol\u00edtica:<\/p>\n<p>&#8211; Divulga\u00e7\u00e3o de informa\u00e7\u00f5es pessoais sens\u00edveis sobre os outros.<br \/>&#8211; Recolher ou tentar recolher informa\u00e7\u00f5es pessoais sobre terceiros sem o seu conhecimento ou consentimento.<br \/>&#8211; Amea\u00e7ar danos a pessoas ou bens ou de outro modo assediar comportamentos.<br \/>&#8211; Cart\u00e3o de cr\u00e9dito manual ou autom\u00e1tico ou outros m\u00e9todos de pagamento dispon\u00edveis que testes com bots ou scripts.<br \/>&#8211; Comprando qualquer um dos servi\u00e7os oferecidos em nome de outra pessoa.<br \/>&#8211; Deturpa\u00e7\u00e3o ou representa\u00e7\u00e3o fraudulenta de produtos ou servi\u00e7os.<br \/>&#8211; Infringir a propriedade intelectual ou outros direitos de propriedade de outros.<br \/>&#8211; Facilitar, ajudar ou incentivar qualquer uma das atividades acima referidas atrav\u00e9s do Website e Servi\u00e7os.<\/p>\n<p><strong>Abuso de sistema<\/strong><\/p>\n<p>Qualquer Utilizador que violar a seguran\u00e7a do Website e servi\u00e7os est\u00e1 sujeito a responsabilidade criminal e civil, bem como a rescis\u00e3o imediata da conta. Exemplos incluem, mas n\u00e3o se limitam ao seguinte:<\/p>\n<p>&#8211; Utiliza\u00e7\u00e3o ou distribui\u00e7\u00e3o de ferramentas concebidas para comprometer a seguran\u00e7a do Website e Servi\u00e7os.<br \/>&#8211; Transmitir intencionalmente ou negligentemente ficheiros contendo um v\u00edrus inform\u00e1tico ou dados corrompidos.<br \/>&#8211; Aceder a outra rede sem permiss\u00e3o, incluindo sondar ou procurar por vulnerabilidades ou violar medidas de seguran\u00e7a ou de autentica\u00e7\u00e3o.<br \/>&#8211; Digitaliza\u00e7\u00e3o ou monitoriza\u00e7\u00e3o n\u00e3o autorizada de dados em qualquer rede ou sistema sem a devida autoriza\u00e7\u00e3o do propriet\u00e1rio do sistema ou rede.<\/p>\n<p><strong>Recursos de servi\u00e7o<\/strong><\/p>\n<p>N\u00e3o pode consumir quantidades excessivas dos recursos do Website e Servi\u00e7os ou utilizar o Website e Servi\u00e7os de qualquer forma que resulte em problemas de desempenho ou que interrompa os Servi\u00e7os para outros Utilizadores. As atividades proibidas que contribuem para o uso excessivo, incluem, sem limita\u00e7\u00e3o:<\/p>\n<p>&#8211; Tentativas deliberadas de sobrecarregar o Website e Servi\u00e7os e transmitir ataques (isto \u00e9, ataques de nega\u00e7\u00e3o de servi\u00e7o).<br \/>&#8211; Participa\u00e7\u00e3o em quaisquer outras atividades que degradem a usabilidade e desempenho do Website e Servi\u00e7os.<\/p>\n<p><strong>Execu\u00e7\u00e3o<\/strong><\/p>\n<p>Reservamo-nos o direito de ser o \u00fanico \u00e1rbitro na determina\u00e7\u00e3o da gravidade de cada infra\u00e7\u00e3o e em tomar imediatamente medidas corretivas, incluindo, mas n\u00e3o se limitando a:<\/p>\n<p>&#8211; Suspender ou encerrar o seu Servi\u00e7o com ou sem aviso pr\u00e9vio sobre qualquer viola\u00e7\u00e3o desta Pol\u00edtica.<br \/>&#8211; Desativar ou remover qualquer conte\u00fado que seja proibido por esta Pol\u00edtica, incluindo para evitar danos a outros ou a n\u00f3s ou ao Website e Servi\u00e7os, conforme determinado por n\u00f3s a nosso exclusivo crit\u00e9rio.<br \/>&#8211; Relatar viola\u00e7\u00f5es \u00e0s for\u00e7as da lei, como determinado por n\u00f3s, a nosso exclusivo crit\u00e9rio.<\/p>\n<p>Nada contido nesta pol\u00edtica deve ser interpretado para limitar as nossas a\u00e7\u00f5es ou solu\u00e7\u00f5es em rela\u00e7\u00e3o a qualquer das atividades proibidas. Reservamo-nos o direito de tomar todas e quaisquer a\u00e7\u00f5es adicionais que consideremos adequadas em rela\u00e7\u00e3o a tais atividades, incluindo, sem limita\u00e7\u00e3o, tomar medidas para recuperar os custos e despesas de identifica\u00e7\u00e3o dos infratores e remov\u00ea-los do Website e Servi\u00e7os, e cobrar taxas de cancelamento para cobrir os nossos custos. Al\u00e9m disso, reservamos sempre todos os direitos e recursos de que dispomos no que diz respeito a tais atividades legais ou de equidade.<\/p>\n<p><strong>Den\u00fancia de viola\u00e7\u00f5es<\/strong><\/p>\n<p>Se descobriu e gostaria de denunciar uma viola\u00e7\u00e3o desta Pol\u00edtica, contacte-nos imediatamente. Vamos investigar a situa\u00e7\u00e3o e prestar-lhe toda a assist\u00eancia.<\/p>\n<p><strong>Altera\u00e7\u00f5es e altera\u00e7\u00f5es<\/strong><\/p>\n<p>Reservamo-nos o direito de modificar esta Pol\u00edtica ou os seus termos relativos ao Website e Servi\u00e7os a qualquer momento, com efeito ap\u00f3s a publica\u00e7\u00e3o de uma vers\u00e3o atualizada desta Pol\u00edtica no Website. Quando o fizermos, reveremos a data atualizada na parte inferior desta p\u00e1gina. A continua\u00e7\u00e3o da utiliza\u00e7\u00e3o do Website e dos Servi\u00e7os ap\u00f3s tais altera\u00e7\u00f5es constituir\u00e1 o seu consentimento para tais altera\u00e7\u00f5es.<\/p>\n<p><strong>Aceita\u00e7\u00e3o desta pol\u00edtica<\/strong><\/p>\n<p>Reconhece que leu esta Pol\u00edtica e concorda com todos os seus termos e condi\u00e7\u00f5es. Ao aceder e utilizar o Website e Servi\u00e7os, concorda em ficar vinculado a esta Pol\u00edtica. Caso n\u00e3o concorde em respeitar os termos desta Pol\u00edtica, n\u00e3o est\u00e1 autorizado a aceder ou utilizar o Website e Servi\u00e7os.<\/p>\n<p><strong>Contate-nos<\/strong><\/p>\n<p>Se quiser contactar-nos para saber mais sobre esta Pol\u00edtica ou pretender contactar-nos sobre qualquer assunto que lhe seja relacionado, poder\u00e1 faz\u00ea-lo atrav\u00e9s do formul\u00e1rio de contacto, enviar um e-mail para contact@healthcliner.com ou escrever uma carta para 441 Fairview Avenue, Bridgeport, CT 06606, EUA.<\/p>\n<p><strong>Este documento foi atualizado pela \u00faltima vez em 4 de junho de 2021<\/strong><\/p>\n<p><a href=\"https:\/\/www.websitepolicies.com\/policies\/view\/7KXlMwcR\" target=\"_blank\" rel=\"noopener\"><strong>https:\/\/www.websitepolicies.com\/policies\/view\/7KXlMwcR<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pol\u00edtica do DMCA<\/strong><\/p>\n<p>Esta pol\u00edtica digital da Lei de Direitos de Autor (&#8220;Pol\u00edtica&#8221;) aplica-se ao website healthcliner.com (&#8220;Website&#8221; ou &#8220;Servi\u00e7o&#8221;) e a qualquer um dos seus produtos e servi\u00e7os relacionados (coletivamente, &#8220;Servi\u00e7os&#8221;) e descreve como a Healthcliner (&#8220;Healthcliner&#8221;, &#8220;n\u00f3s&#8221;, &#8220;n\u00f3s&#8221; ou &#8220;nosso&#8221;) aborda as notifica\u00e7\u00f5es de viola\u00e7\u00e3o de direitos de autor e como voc\u00ea (&#8220;voc\u00ea&#8221; ou &#8220;seu&#8221;) pode apresentar uma queixa por direitos de autor.<\/p>\n<p>A prote\u00e7\u00e3o da propriedade intelectual \u00e9 da maior import\u00e2ncia para n\u00f3s e pedimos aos nossos utilizadores e aos seus agentes autorizados que fa\u00e7am o mesmo. \u00c9 nossa pol\u00edtica responder rapidamente a notifica\u00e7\u00f5es claras de alegada viola\u00e7\u00e3o de direitos de autor que cumprem a Lei de Direitos de Autor do Mil\u00e9nio Digital dos Estados Unidos (&#8220;DMCA&#8221;) de 1998, que o texto pode ser encontrado no site do U.S. Copyright Office.<\/p>\n<p><strong>O que considerar antes de apresentar uma queixa de direitos de autor<\/strong><\/p>\n<p>Por favor, note que abaixo dos 17 U.S..C. \u00a7 512(f), voc\u00ea pode ser respons\u00e1vel por qualquer dano, incluindo custos e honor\u00e1rios de advogados incorridos por n\u00f3s ou pelos nossos utilizadores, se voc\u00ea conscientemente deturpar que o material ou atividade est\u00e1 infringindo. Se n\u00e3o tiver a certeza se o material que est\u00e1 a reportar est\u00e1 de facto a infringir, poder\u00e1 pretender contactar um advogado antes de apresentar uma notifica\u00e7\u00e3o connosco.<\/p>\n<p>O DMCA exige que forne\u00e7a as suas informa\u00e7\u00f5es pessoais na notifica\u00e7\u00e3o de viola\u00e7\u00e3o de direitos de autor. Se estiver preocupado com a privacidade das suas informa\u00e7\u00f5es pessoais, poder\u00e1 pretender contratar um agente para denunciar o material infringido por si.<\/p>\n<p><strong>Notifica\u00e7\u00f5es de infra\u00e7\u00e3o<\/strong><\/p>\n<p>Se voc\u00ea \u00e9 um propriet\u00e1rio de direitos autorais ou um agente dos mesmos, e voc\u00ea acredita que qualquer material dispon\u00edvel nos nossos Servi\u00e7os infringe os seus direitos de autor, ent\u00e3o voc\u00ea pode submeter uma notifica\u00e7\u00e3o por viola\u00e7\u00e3o de direitos de autor escrito (&#8220;Notifica\u00e7\u00e3o&#8221;) usando os dados de contato abaixo de acordo com o DMCA, fornecendo-nos as seguintes informa\u00e7\u00f5es:<\/p>\n<p>&#8211; Identifica\u00e7\u00e3o do trabalho com direitos de autor que alega ter sido infringido, ou, se v\u00e1rias obras com direitos de autor estiverem cobertas por esta Notifica\u00e7\u00e3o, poder\u00e1 fornecer uma lista representativa das obras com direitos de autor que alega terem sido infringidas.<br \/>&#8211; A identifica\u00e7\u00e3o do material infrator e das informa\u00e7\u00f5es que afirma estar a infringir (ou o objeto de atividade infringida), incluindo, no m\u00ednimo, se aplic\u00e1vel, o URL ou URLs das p\u00e1ginas web onde o material alegadamente infringido pode ser encontrado.<br \/>&#8211; Informa\u00e7\u00f5es razoavelmente suficientes para nos permitir contact\u00e1-lo, como endere\u00e7o, n\u00famero de telefone e, se dispon\u00edvel, um endere\u00e7o de e-mail.<br \/>&#8211; Uma declara\u00e7\u00e3o de que tem uma boa f\u00e9 de que o uso do material da forma reclamada n\u00e3o \u00e9 autorizado pelo propriet\u00e1rio dos direitos de autor, pelo agente do titular dos direitos de autor ou pela lei.<br \/>&#8211; Uma declara\u00e7\u00e3o de que as informa\u00e7\u00f5es na notifica\u00e7\u00e3o s\u00e3o exatas e, sob pena de perj\u00fario, est\u00e1 autorizado a agir em nome do propriet\u00e1rio de um direito exclusivo que \u00e9 alegadamente violado.<br \/>&#8211; Basta uma assinatura f\u00edsica ou electr\u00f3nica (digitando o seu nome completo) do titular dos direitos de autor ou de uma pessoa autorizada a agir em seu nome.<\/p>\n<p>Todas estas notifica\u00e7\u00f5es devem estar em conformidade com os requisitos do DMCA. Pode consultar um gerador de aviso de retirada DMCA ou outros servi\u00e7os similares para evitar cometer erros e garantir o cumprimento da sua Notifica\u00e7\u00e3o.<\/p>\n<p>Apresentar uma reclama\u00e7\u00e3o de DMCA \u00e9 o in\u00edcio de um processo legal pr\u00e9-definido. A sua reclama\u00e7\u00e3o ser\u00e1 revista com precis\u00e3o, validade e completude. Se a sua reclama\u00e7\u00e3o tiver preenchido estes requisitos, a nossa resposta pode incluir a remo\u00e7\u00e3o ou restri\u00e7\u00e3o de acesso a material alegadamente infringido.<\/p>\n<p>Se removermos ou restringirmos o acesso a materiais ou encerrarmos uma conta em resposta a uma Notifica\u00e7\u00e3o de alegada infra\u00e7\u00e3o, faremos um esfor\u00e7o de boa f\u00e9 para contactar o utilizador afetado com informa\u00e7\u00f5es sobre a remo\u00e7\u00e3o ou restri\u00e7\u00e3o de acesso.<\/p>\n<p>N\u00e3o obstante o contr\u00e1rio contido em qualquer parte da presente Pol\u00edtica, o Healthcliner reserva-se o direito de n\u00e3o tomar qualquer medida ap\u00f3s a rece\u00e7\u00e3o de uma notifica\u00e7\u00e3o de viola\u00e7\u00e3o de direitos de autor da DMCA se n\u00e3o cumprir todos os requisitos do DMCA para tais notifica\u00e7\u00f5es.<\/p>\n<p>O processo descrito nesta Pol\u00edtica n\u00e3o limita a nossa capacidade de prosseguir quaisquer outras vias de recurso que possamos ter de resolver suspeitas de infra\u00e7\u00e3o.<\/p>\n<p><strong>Altera\u00e7\u00f5es e altera\u00e7\u00f5es<\/strong><\/p>\n<p>Reservamo-nos o direito de modificar esta Pol\u00edtica ou os seus termos relativos ao Website e Servi\u00e7os a qualquer momento, com efeito ap\u00f3s a publica\u00e7\u00e3o de uma vers\u00e3o atualizada desta Pol\u00edtica no Website. Quando o fizermos, reveremos a data atualizada na parte inferior desta p\u00e1gina.<\/p>\n<p><strong>Infra\u00e7\u00e3o de direitos autorais<\/strong><\/p>\n<p>Se quiser notificar-nos do material ou atividade infrator, poder\u00e1 faz\u00ea-lo atrav\u00e9s do formul\u00e1rio de contacto, enviar um e-mail para contact@healthcliner.com ou escrever uma carta para 441 Fairview Avenue, Bridgeport, CT 06606, EUA.<\/p>\n<p><strong>Este documento foi atualizado pela \u00faltima vez em 3 de junho de 2021<\/strong><\/p>\n<p><a href=\"https:\/\/www.websitepolicies.com\/policies\/view\/LzY8IBTg\" target=\"_blank\" rel=\"noopener\"><strong><a>https:\/\/www.websitepolicies.com\/policies\/view\/LzY8IBTg<\/a><\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pol\u00edtica de reembolso<\/strong><\/p>\n<p>Uma vez que o Website oferece bens n\u00e3o tang\u00edveis e irrevog\u00e1veis n\u00e3o fornecemos reembolsos ap\u00f3s a compra do produto, o que reconhece antes de comprar qualquer produto no Website. Por favor, certifique-se de que leu cuidadosamente a descri\u00e7\u00e3o do servi\u00e7o antes de fazer uma compra.<\/p>\n<p><strong>Contate-nos<\/strong><\/p>\n<p>Se quiser contactar-nos sobre qualquer assunto relacionado com esta Pol\u00edtica de Reembolso, poder\u00e1 faz\u00ea-lo atrav\u00e9s do formul\u00e1rio de contacto, enviar um e-mail para contact@healthcliner.com ou escrever uma carta para 441 Fairview Avenue, Bridgeport, CT 06606, EUA<\/p>\n<p><strong>Este documento foi atualizado pela \u00faltima vez em 3 de junho de 2021<\/strong><\/p>\n<p><a href=\"https:\/\/www.websitepolicies.com\/policies\/view\/JMthXT9F\" target=\"_blank\" rel=\"noopener\"><strong>https:\/\/www.websitepolicies.com\/policies\/view\/JMthXT9F<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pol\u00edtica de cookies<\/strong><\/p>\n<p>Esta pol\u00edtica de cookies (&#8220;Pol\u00edtica&#8221;) descreve o que s\u00e3o e como s\u00e3o os cookies e como est\u00e3o a ser utilizados pelo website healthcliner.com (&#8220;Website&#8221; ou &#8220;Servi\u00e7o&#8221;) e qualquer um dos seus produtos e servi\u00e7os relacionados (coletivamente, &#8220;Servi\u00e7os&#8221;). Esta Pol\u00edtica \u00e9 um acordo juridicamente vinculativo entre si (&#8220;Utilizador&#8221;, &#8220;voc\u00ea&#8221; ou &#8220;seu&#8221;) e Healthcliner (&#8220;Healthcliner&#8221;, &#8220;n\u00f3s&#8221;, &#8220;n\u00f3s&#8221; ou &#8220;nosso&#8221;). Voc\u00ea deve ler esta Pol\u00edtica para que voc\u00ea possa entender os tipos de cookies que usamos, as informa\u00e7\u00f5es que recolhemos usando cookies e como essa informa\u00e7\u00e3o \u00e9 usada. Tamb\u00e9m descreve as escolhas dispon\u00edveis para aceitar ou recusar o uso de cookies. Para mais informa\u00e7\u00f5es sobre como utilizamos, armazenar e manter os seus dados pessoais seguros, consulte a nossa pol\u00edtica de privacidade.<\/p>\n<p><strong>O que s\u00e3o biscoitos?<\/strong><\/p>\n<p>Os cookies s\u00e3o pequenos peda\u00e7os de dados armazenados em ficheiros de texto que s\u00e3o guardados no seu computador ou outros dispositivos quando os websites s\u00e3o carregados num browser. Eles s\u00e3o amplamente utilizados para lembrar voc\u00ea e suas prefer\u00eancias, seja para uma \u00fanica visita (atrav\u00e9s de um &#8220;cookie de sess\u00e3o&#8221;) ou para m\u00faltiplas visitas repetidas (usando um &#8220;cookie persistente&#8221;).<\/p>\n<p>Os cookies de sess\u00e3o s\u00e3o cookies tempor\u00e1rios que s\u00e3o usados durante a sua visita ao Site, e expiram quando voc\u00ea fecha o navegador web.<\/p>\n<p>Os cookies persistentes s\u00e3o utilizados para lembrar as suas prefer\u00eancias dentro do nosso Website e permanecer no seu ambiente de trabalho ou dispositivo m\u00f3vel mesmo depois de fechar o seu navegador ou reiniciar o seu computador. Garantem uma experi\u00eancia consistente e eficiente para si durante a visita ao Website e Servi\u00e7os.<\/p>\n<p>Os cookies podem ser definidos pelo Website (&#8220;cookies de primeira parte&#8221;), ou por terceiros, como aqueles que servem conte\u00fados ou prestam servi\u00e7os de publicidade ou anal\u00edtica no Website (&#8220;cookies de terceiros&#8221;). Estes terceiros podem reconhec\u00ea-lo quando visita o nosso site e tamb\u00e9m quando visita determinados outros websites. Voc\u00ea pode aprender mais sobre cookies e como eles funcionam aqui.<\/p>\n<p><strong>Que tipo de cookies usamos?<\/strong><\/p>\n<p>&#8211; Cookies necess\u00e1rios<\/p>\n<p>Os cookies necess\u00e1rios permitem-nos oferecer-lhe a melhor experi\u00eancia poss\u00edvel ao aceder e navegar atrav\u00e9s do nosso Website e utilizar as suas funcionalidades. Por exemplo, estes cookies permitem-nos reconhecer que criou uma conta e que entrou nessa conta para aceder ao conte\u00fado.<\/p>\n<p>&#8211; Cookies de funcionalidade<\/p>\n<p>Os cookies de funcionalidade permitem-nos operar o Website e os Servi\u00e7os de acordo com as escolhas que faz. Por exemplo, reconheceremos o seu nome de utilizador e lembraremos como personalizou o Website e os Servi\u00e7os durante futuras visitas.<\/p>\n<p>Quais s\u00e3o as suas op\u00e7\u00f5es de cookies?<\/p>\n<p>Se n\u00e3o gosta da ideia de cookies ou certos tipos de cookies, pode alterar as defini\u00e7\u00f5es do seu navegador para eliminar cookies que j\u00e1 foram definidos e n\u00e3o aceitar novos cookies. Para saber mais sobre como faz\u00ea-lo, visite internetcookies.com<\/p>\n<p>Por favor, note, no entanto, que se eliminar cookies ou n\u00e3o os aceitar, poder\u00e1 n\u00e3o conseguir utilizar todas as funcionalidades que o Website e Servi\u00e7os oferecem.<\/p>\n<p><strong>Altera\u00e7\u00f5es e altera\u00e7\u00f5es<\/strong><\/p>\n<p>Reservamo-nos o direito de modificar esta Pol\u00edtica ou os seus termos relativos ao Website e Servi\u00e7os a qualquer momento, com efeito ap\u00f3s a publica\u00e7\u00e3o de uma vers\u00e3o atualizada desta Pol\u00edtica no Website. Quando o fizermos, reveremos a data atualizada na parte inferior desta p\u00e1gina. A continua\u00e7\u00e3o da utiliza\u00e7\u00e3o do Website e dos Servi\u00e7os ap\u00f3s tais altera\u00e7\u00f5es constituir\u00e1 o seu consentimento para tais altera\u00e7\u00f5es.<\/p>\n<p><strong>Aceita\u00e7\u00e3o desta pol\u00edtica<\/strong><\/p>\n<p>Reconhece que leu esta Pol\u00edtica e concorda com todos os seus termos e condi\u00e7\u00f5es. Ao aceder e utilizar o Website e Servi\u00e7os, concorda em ficar vinculado a esta Pol\u00edtica. Caso n\u00e3o concorde em respeitar os termos desta Pol\u00edtica, n\u00e3o est\u00e1 autorizado a aceder ou utilizar o Website e Servi\u00e7os.<\/p>\n<p><strong>Contate-nos<\/strong><\/p>\n<p>Se quiser contactar-nos para saber mais sobre esta Pol\u00edtica ou pretender contactar-nos sobre qualquer assunto relacionado com a nossa utiliza\u00e7\u00e3o de cookies, poder\u00e1 faz\u00ea-lo atrav\u00e9s do formul\u00e1rio de contacto, enviar um e-mail para contact@healthcliner.com ou escrever uma carta para 441 Fairview Avenue, Bridgeport, CT 06606, EUA.<\/p>\n<p><strong>Este documento foi atualizado pela \u00faltima vez em 4 de junho de 2021<\/strong><\/p>\n<p><a href=\"https:\/\/www.websitepolicies.com\/policies\/view\/f9Ycmm3p\" target=\"_blank\" rel=\"noopener\"><strong>https:\/\/www.websitepolicies.com\/policies\/view\/f9Ycmm3p<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-2vw||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto||||||||&#8221; text_text_color=&#8221;rgba(0,0,0,0.75)&#8221; text_font_size=&#8221;16px&#8221; link_font=&#8221;Roboto||||||||&#8221; link_text_color=&#8221;#68d800&#8243; link_font_size=&#8221;16px&#8221; link_option_url=&#8221;https:\/\/www.websitepolicies.com\/policies\/view\/7KXlMwcR&#8221; link_option_url_new_window=&#8221;on&#8221; link_text_color__hover_enabled=&#8221;off|hover&#8221;] Pol\u00edtica de utiliza\u00e7\u00e3o aceit\u00e1vel Esta pol\u00edtica de utiliza\u00e7\u00e3o aceit\u00e1vel (&#8220;Pol\u00edtica&#8221;) estabelece as orienta\u00e7\u00f5es gerais e as utiliza\u00e7\u00f5es aceit\u00e1veis e proibidas do website [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"class_list":["post-6499","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regras e Regulamentos - Healthcliner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/healthcliner.com\/pt-pt\/regras-e-regulamentos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regras e Regulamentos - Healthcliner\" \/>\n<meta property=\"og:description\" content=\"[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-2vw||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto||||||||&#8221; text_text_color=&#8221;rgba(0,0,0,0.75)&#8221; text_font_size=&#8221;16px&#8221; link_font=&#8221;Roboto||||||||&#8221; link_text_color=&#8221;#68d800&#8243; link_font_size=&#8221;16px&#8221; link_option_url=&#8221;https:\/\/www.websitepolicies.com\/policies\/view\/7KXlMwcR&#8221; link_option_url_new_window=&#8221;on&#8221; link_text_color__hover_enabled=&#8221;off|hover&#8221;] Pol\u00edtica de utiliza\u00e7\u00e3o aceit\u00e1vel Esta pol\u00edtica de utiliza\u00e7\u00e3o aceit\u00e1vel (&#8220;Pol\u00edtica&#8221;) estabelece as orienta\u00e7\u00f5es gerais e as utiliza\u00e7\u00f5es aceit\u00e1veis e proibidas do website [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/healthcliner.com\/pt-pt\/regras-e-regulamentos\/\" \/>\n<meta property=\"og:site_name\" content=\"Healthcliner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/Healthcliner\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-10T08:31:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@healthcliner\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/regras-e-regulamentos\\\/\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/regras-e-regulamentos\\\/\",\"name\":\"Regras e Regulamentos - Healthcliner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2021-08-10T08:31:10+00:00\",\"dateModified\":\"2021-08-10T08:31:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/regras-e-regulamentos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/regras-e-regulamentos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/regras-e-regulamentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regras e Regulamentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/\",\"name\":\"Healthcliner\",\"description\":\"Evidence-based Health Information\",\"publisher\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#organization\",\"name\":\"Healthcliner\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Small-size-transparent-image-for-web-1.png\",\"contentUrl\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Small-size-transparent-image-for-web-1.png\",\"width\":500,\"height\":101,\"caption\":\"Healthcliner\"},\"image\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/Healthcliner\",\"https:\\\/\\\/x.com\\\/healthcliner\",\"https:\\\/\\\/www.instagram.com\\\/healthcliner\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/Healthcliner\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regras e Regulamentos - Healthcliner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/healthcliner.com\/pt-pt\/regras-e-regulamentos\/","og_locale":"pt_PT","og_type":"article","og_title":"Regras e Regulamentos - Healthcliner","og_description":"[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-2vw||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto||||||||&#8221; text_text_color=&#8221;rgba(0,0,0,0.75)&#8221; text_font_size=&#8221;16px&#8221; link_font=&#8221;Roboto||||||||&#8221; link_text_color=&#8221;#68d800&#8243; link_font_size=&#8221;16px&#8221; link_option_url=&#8221;https:\/\/www.websitepolicies.com\/policies\/view\/7KXlMwcR&#8221; link_option_url_new_window=&#8221;on&#8221; link_text_color__hover_enabled=&#8221;off|hover&#8221;] Pol\u00edtica de utiliza\u00e7\u00e3o aceit\u00e1vel Esta pol\u00edtica de utiliza\u00e7\u00e3o aceit\u00e1vel (&#8220;Pol\u00edtica&#8221;) estabelece as orienta\u00e7\u00f5es gerais e as utiliza\u00e7\u00f5es aceit\u00e1veis e proibidas do website [&hellip;]","og_url":"https:\/\/healthcliner.com\/pt-pt\/regras-e-regulamentos\/","og_site_name":"Healthcliner","article_publisher":"https:\/\/business.facebook.com\/Healthcliner","article_modified_time":"2021-08-10T08:31:23+00:00","twitter_card":"summary_large_image","twitter_site":"@healthcliner","twitter_misc":{"Tempo estimado de leitura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/healthcliner.com\/pt-pt\/regras-e-regulamentos\/","url":"https:\/\/healthcliner.com\/pt-pt\/regras-e-regulamentos\/","name":"Regras e Regulamentos - Healthcliner","isPartOf":{"@id":"https:\/\/healthcliner.com\/pt-pt\/#website"},"datePublished":"2021-08-10T08:31:10+00:00","dateModified":"2021-08-10T08:31:23+00:00","breadcrumb":{"@id":"https:\/\/healthcliner.com\/pt-pt\/regras-e-regulamentos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/healthcliner.com\/pt-pt\/regras-e-regulamentos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/healthcliner.com\/pt-pt\/regras-e-regulamentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/healthcliner.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Regras e Regulamentos"}]},{"@type":"WebSite","@id":"https:\/\/healthcliner.com\/pt-pt\/#website","url":"https:\/\/healthcliner.com\/pt-pt\/","name":"Healthcliner","description":"Evidence-based Health Information","publisher":{"@id":"https:\/\/healthcliner.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/healthcliner.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/healthcliner.com\/pt-pt\/#organization","name":"Healthcliner","url":"https:\/\/healthcliner.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/healthcliner.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/09\/Small-size-transparent-image-for-web-1.png","contentUrl":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/09\/Small-size-transparent-image-for-web-1.png","width":500,"height":101,"caption":"Healthcliner"},"image":{"@id":"https:\/\/healthcliner.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/Healthcliner","https:\/\/x.com\/healthcliner","https:\/\/www.instagram.com\/healthcliner\/","https:\/\/www.pinterest.com\/Healthcliner\/"]}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/pages\/6499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=6499"}],"version-history":[{"count":5,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/pages\/6499\/revisions"}],"predecessor-version":[{"id":6504,"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/pages\/6499\/revisions\/6504"}],"wp:attachment":[{"href":"https:\/\/healthcliner.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=6499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}