{"id":129,"count":40,"description":"","link":"https:\/\/healthcliner.com\/it\/category\/articoli\/","name":"Articoli","slug":"articoli","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Articoli Archives - Healthcliner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/healthcliner.com\/it\/category\/articoli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Articoli Archives - Healthcliner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/healthcliner.com\/it\/category\/articoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Healthcliner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@healthcliner\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/category\\\/articoli\\\/\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/category\\\/articoli\\\/\",\"name\":\"Articoli Archives - Healthcliner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/category\\\/articoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/category\\\/articoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/\",\"name\":\"Healthcliner\",\"description\":\"Evidence-based Health Information\",\"publisher\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/#organization\",\"name\":\"Healthcliner\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Small-size-transparent-image-for-web-1.png\",\"contentUrl\":\"https:\\\/\\\/healthcliner.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Small-size-transparent-image-for-web-1.png\",\"width\":500,\"height\":101,\"caption\":\"Healthcliner\"},\"image\":{\"@id\":\"https:\\\/\\\/healthcliner.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/Healthcliner\",\"https:\\\/\\\/x.com\\\/healthcliner\",\"https:\\\/\\\/www.instagram.com\\\/healthcliner\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/Healthcliner\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Articoli Archives - Healthcliner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/healthcliner.com\/it\/category\/articoli\/","og_locale":"it_IT","og_type":"article","og_title":"Articoli Archives - Healthcliner","og_url":"https:\/\/healthcliner.com\/it\/category\/articoli\/","og_site_name":"Healthcliner","twitter_card":"summary_large_image","twitter_site":"@healthcliner","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/healthcliner.com\/it\/category\/articoli\/","url":"https:\/\/healthcliner.com\/it\/category\/articoli\/","name":"Articoli Archives - Healthcliner","isPartOf":{"@id":"https:\/\/healthcliner.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/healthcliner.com\/it\/category\/articoli\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/healthcliner.com\/it\/category\/articoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/healthcliner.com\/it\/"},{"@type":"ListItem","position":2,"name":"Articoli"}]},{"@type":"WebSite","@id":"https:\/\/healthcliner.com\/it\/#website","url":"https:\/\/healthcliner.com\/it\/","name":"Healthcliner","description":"Evidence-based Health Information","publisher":{"@id":"https:\/\/healthcliner.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/healthcliner.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/healthcliner.com\/it\/#organization","name":"Healthcliner","url":"https:\/\/healthcliner.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/healthcliner.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/09\/Small-size-transparent-image-for-web-1.png","contentUrl":"https:\/\/healthcliner.com\/wp-content\/uploads\/2021\/09\/Small-size-transparent-image-for-web-1.png","width":500,"height":101,"caption":"Healthcliner"},"image":{"@id":"https:\/\/healthcliner.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/Healthcliner","https:\/\/x.com\/healthcliner","https:\/\/www.instagram.com\/healthcliner\/","https:\/\/www.pinterest.com\/Healthcliner\/"]}]}},"_links":{"self":[{"href":"https:\/\/healthcliner.com\/it\/wp-json\/wp\/v2\/categories\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/healthcliner.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/healthcliner.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/healthcliner.com\/it\/wp-json\/wp\/v2\/posts?categories=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}